{"id":4133,"date":"2022-12-26T13:41:00","date_gmt":"2022-12-26T12:41:00","guid":{"rendered":"https:\/\/www.deltavissers.nl\/?p=4133"},"modified":"2022-12-26T15:15:55","modified_gmt":"2022-12-26T14:15:55","slug":"rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud","status":"publish","type":"post","link":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/","title":{"rendered":"UPDATE &#8211; RWS-steiger en loopbrug Neeltje Jans in onderhoud"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4133\" class=\"elementor elementor-4133\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-97a1e18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"13726\" data-id=\"97a1e18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e23240\" data-eae-slider=\"51204\" data-id=\"1e23240\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-133a22d elementor-widget elementor-widget-heading\" data-id=\"133a22d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">UPDATE<br>\nRWS-steiger en loopbrug Neeltje Jans in onderhoud<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-ee75679 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"79917\" data-id=\"ee75679\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5ac4d9\" data-eae-slider=\"3691\" data-id=\"b5ac4d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed9af62 elementor-widget elementor-widget-image\" data-id=\"ed9af62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"370\" src=\"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten.jpg\" class=\"attachment-full size-full wp-image-4135\" alt=\"\" srcset=\"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten.jpg 750w, https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten-300x148.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" loading=\"eager\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-cfdbd6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"34496\" data-id=\"cfdbd6c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e70ea8\" data-eae-slider=\"4907\" data-id=\"9e70ea8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed02e3b elementor-widget elementor-widget-text-editor\" data-id=\"ed02e3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">In april 2023 wordt de wachtsteiger in de buitenhaven van Neeltje Jans compleet gedemonteerd. De palen worden gewisseld voor nieuwe, definitieve palen en vervolgens worden de brugdelen + wachtsteigers teruggeplaatst.\u00a0Uitgangspunt hierbij is dat deze aanleginrichting voor 1 mei weer functioneel is met uitzondering van de elektravoorzieningen.<\/p><p style=\"text-align: justify;\">In het najaar worden het ponton, brugdeel en wachtsteigers weer opgenomen voor renovatie. In de beide periodes dat dit gebeurt, zal onze op- en afstapsteiger niet beschikbaar zijn. Details voor het najaar volgen tegen de tijd dat de werken aanvangen.<\/p><hr \/><p style=\"text-align: justify;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>UPDATE RWS-steiger en loopbrug Neeltje Jans in onderhoud In april 2023 wordt de wachtsteiger in de buitenhaven van Neeltje Jans&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":4428,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[27,184],"class_list":["post-4133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actueel","tag-neeltje-jans","tag-werken-steigers"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UPDATE - RWS-steiger en loopbrug Neeltje Jans in onderhoud - Deltavissers Digitaal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UPDATE - RWS-steiger en loopbrug Neeltje Jans in onderhoud - Deltavissers Digitaal\" \/>\n<meta property=\"og:description\" content=\"UPDATE RWS-steiger en loopbrug Neeltje Jans in onderhoud In april 2023 wordt de wachtsteiger in de buitenhaven van Neeltje Jans&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/\" \/>\n<meta property=\"og:site_name\" content=\"Deltavissers Digitaal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deltavissers-964812903597229\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-26T12:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-26T14:15:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactie Deltavissers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactie Deltavissers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/\"},\"author\":{\"name\":\"Redactie Deltavissers\",\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/#\\\/schema\\\/person\\\/0e0e972c446ec31008f495a8e2fe2add\"},\"headline\":\"UPDATE &#8211; RWS-steiger en loopbrug Neeltje Jans in onderhoud\",\"datePublished\":\"2022-12-26T12:41:00+00:00\",\"dateModified\":\"2022-12-26T14:15:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/\"},\"wordCount\":102,\"image\":{\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deltavissers.nl\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg\",\"keywords\":[\"Neeltje Jans\",\"werken steigers\"],\"articleSection\":[\"Actueel\"],\"inLanguage\":\"nl-BE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/\",\"url\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/\",\"name\":\"UPDATE - RWS-steiger en loopbrug Neeltje Jans in onderhoud - Deltavissers Digitaal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deltavissers.nl\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg\",\"datePublished\":\"2022-12-26T12:41:00+00:00\",\"dateModified\":\"2022-12-26T14:15:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/#\\\/schema\\\/person\\\/0e0e972c446ec31008f495a8e2fe2add\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deltavissers.nl\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deltavissers.nl\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg\",\"width\":350,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/index.php\\\/2022\\\/12\\\/26\\\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.deltavissers.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UPDATE &#8211; RWS-steiger en loopbrug Neeltje Jans in onderhoud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/#website\",\"url\":\"https:\\\/\\\/www.deltavissers.nl\\\/\",\"name\":\"Deltavissers Digitaal\",\"description\":\"Webstek van Bootvisvereniging Zuid-West Nederland\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deltavissers.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deltavissers.nl\\\/#\\\/schema\\\/person\\\/0e0e972c446ec31008f495a8e2fe2add\",\"name\":\"Redactie Deltavissers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g\",\"caption\":\"Redactie Deltavissers\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UPDATE - RWS-steiger en loopbrug Neeltje Jans in onderhoud - Deltavissers Digitaal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/","og_locale":"nl_BE","og_type":"article","og_title":"UPDATE - RWS-steiger en loopbrug Neeltje Jans in onderhoud - Deltavissers Digitaal","og_description":"UPDATE RWS-steiger en loopbrug Neeltje Jans in onderhoud In april 2023 wordt de wachtsteiger in de buitenhaven van Neeltje Jans&#46;&#46;&#46;","og_url":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/","og_site_name":"Deltavissers Digitaal","article_publisher":"https:\/\/www.facebook.com\/Deltavissers-964812903597229\/","article_published_time":"2022-12-26T12:41:00+00:00","article_modified_time":"2022-12-26T14:15:55+00:00","og_image":[{"width":750,"height":370,"url":"http:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten.jpg","type":"image\/jpeg"}],"author":"Redactie Deltavissers","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Redactie Deltavissers","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/#article","isPartOf":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/"},"author":{"name":"Redactie Deltavissers","@id":"https:\/\/www.deltavissers.nl\/#\/schema\/person\/0e0e972c446ec31008f495a8e2fe2add"},"headline":"UPDATE &#8211; RWS-steiger en loopbrug Neeltje Jans in onderhoud","datePublished":"2022-12-26T12:41:00+00:00","dateModified":"2022-12-26T14:15:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/"},"wordCount":102,"image":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg","keywords":["Neeltje Jans","werken steigers"],"articleSection":["Actueel"],"inLanguage":"nl-BE"},{"@type":"WebPage","@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/","url":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/","name":"UPDATE - RWS-steiger en loopbrug Neeltje Jans in onderhoud - Deltavissers Digitaal","isPartOf":{"@id":"https:\/\/www.deltavissers.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/#primaryimage"},"image":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg","datePublished":"2022-12-26T12:41:00+00:00","dateModified":"2022-12-26T14:15:55+00:00","author":{"@id":"https:\/\/www.deltavissers.nl\/#\/schema\/person\/0e0e972c446ec31008f495a8e2fe2add"},"breadcrumb":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/#primaryimage","url":"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg","contentUrl":"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg","width":350,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/www.deltavissers.nl\/index.php\/2022\/12\/26\/rws-steiger-en-loopbrug-neeltje-jans-in-onderhoud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deltavissers.nl\/"},{"@type":"ListItem","position":2,"name":"UPDATE &#8211; RWS-steiger en loopbrug Neeltje Jans in onderhoud"}]},{"@type":"WebSite","@id":"https:\/\/www.deltavissers.nl\/#website","url":"https:\/\/www.deltavissers.nl\/","name":"Deltavissers Digitaal","description":"Webstek van Bootvisvereniging Zuid-West Nederland","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deltavissers.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Person","@id":"https:\/\/www.deltavissers.nl\/#\/schema\/person\/0e0e972c446ec31008f495a8e2fe2add","name":"Redactie Deltavissers","image":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/secure.gravatar.com\/avatar\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g","caption":"Redactie Deltavissers"}}]}},"_links":{"self":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/posts\/4133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/comments?post=4133"}],"version-history":[{"count":17,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/posts\/4133\/revisions"}],"predecessor-version":[{"id":4429,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/posts\/4133\/revisions\/4429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/media\/4428"}],"wp:attachment":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/media?parent=4133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/categories?post=4133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/tags?post=4133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}