{"id":5435,"date":"2024-04-22T21:51:31","date_gmt":"2024-04-22T19:51:31","guid":{"rendered":"https:\/\/www.deltavissers.nl\/?p=5435"},"modified":"2024-04-22T21:51:32","modified_gmt":"2024-04-22T19:51:32","slug":"steiger-neeltje-jans-weer-even-buiten-dienst","status":"publish","type":"post","link":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/","title":{"rendered":"Steiger Neeltje Jans weer even buiten dienst"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5435\" class=\"elementor elementor-5435\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-c8927ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"84628\" data-id=\"c8927ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-097decb\" data-eae-slider=\"6196\" data-id=\"097decb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4672648 elementor-widget elementor-widget-heading\" data-id=\"4672648\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Steiger Neeltje Jans weer even buiten dienst<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-709edbc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"14388\" data-id=\"709edbc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4206db0\" data-eae-slider=\"37617\" data-id=\"4206db0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4e5001 elementor-widget elementor-widget-image\" data-id=\"b4e5001\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"370\" src=\"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten.jpg\" class=\"attachment-full size-full wp-image-4135\" alt=\"\" srcset=\"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten.jpg 750w, https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten-300x148.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" loading=\"eager\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-b127d70 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"14113\" data-id=\"b127d70\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1344d36\" data-eae-slider=\"36358\" data-id=\"1344d36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c5eae2 elementor-widget elementor-widget-text-editor\" data-id=\"1c5eae2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\"><strong>Update planning en de uit te voeren werkzaamheden aan de steigers op Neeltje Jans.<\/strong><\/p><p style=\"text-align: justify;\"><em><strong>Wachtsteiger pleziervaart Noordland Binnenhaven:<\/strong><\/em><br \/>De renovatie van de buispalen, opleggingen en brugdelen is reeds voltooid.\u00a0Op maandag 22 april 2024 is gestart met de vervanging van het ponton en de wachtsteigers. Gedurende deze werkzaamheden zal de steiger tijdelijk buiten gebruik zijn, naar verwachting voor een periode van 2-3 dagen.<\/p><p style=\"text-align: justify;\"><em><strong>Wachtsteiger pleziervaart Noordland Buitenhaven:<\/strong><\/em><br \/>Na afronding van de werkzaamheden bij de steiger van Noordland Binnenhaven, zal meteen gestart worden met het vervangen van het ponton en de wachtsteigers bij de Noordland Buitenhaven. Ook hier zal de steiger naar verwachting gedurende 2-3 dagen buiten gebruik zijn.<\/p><hr \/><p style=\"text-align: justify;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Steiger Neeltje Jans weer even buiten dienst Update planning en de uit te voeren werkzaamheden aan de steigers op Neeltje&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":4428,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[222],"class_list":["post-5435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actueel","tag-steiger-neeltje-jans"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Steiger Neeltje Jans weer even buiten dienst - Deltavissers Digitaal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steiger Neeltje Jans weer even buiten dienst - Deltavissers Digitaal\" \/>\n<meta property=\"og:description\" content=\"Steiger Neeltje Jans weer even buiten dienst Update planning en de uit te voeren werkzaamheden aan de steigers op Neeltje&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/\" \/>\n<meta property=\"og:site_name\" content=\"Deltavissers Digitaal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deltavissers-964812903597229\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T19:51:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-22T19:51:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactie Deltavissers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactie Deltavissers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/\"},\"author\":{\"name\":\"Redactie Deltavissers\",\"@id\":\"https:\/\/www.deltavissers.nl\/#\/schema\/person\/0e0e972c446ec31008f495a8e2fe2add\"},\"headline\":\"Steiger Neeltje Jans weer even buiten dienst\",\"datePublished\":\"2024-04-22T19:51:31+00:00\",\"dateModified\":\"2024-04-22T19:51:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/\"},\"wordCount\":120,\"image\":{\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg\",\"keywords\":[\"steiger Neeltje jans\"],\"articleSection\":[\"Actueel\"],\"inLanguage\":\"nl-BE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/\",\"url\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/\",\"name\":\"Steiger Neeltje Jans weer even buiten dienst - Deltavissers Digitaal\",\"isPartOf\":{\"@id\":\"https:\/\/www.deltavissers.nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg\",\"datePublished\":\"2024-04-22T19:51:31+00:00\",\"dateModified\":\"2024-04-22T19:51:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.deltavissers.nl\/#\/schema\/person\/0e0e972c446ec31008f495a8e2fe2add\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#primaryimage\",\"url\":\"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg\",\"contentUrl\":\"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg\",\"width\":350,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.deltavissers.nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steiger Neeltje Jans weer even buiten dienst\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.deltavissers.nl\/#website\",\"url\":\"https:\/\/www.deltavissers.nl\/\",\"name\":\"Deltavissers Digitaal\",\"description\":\"Webstek van Bootvisvereniging Zuid-West Nederland\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.deltavissers.nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.deltavissers.nl\/#\/schema\/person\/0e0e972c446ec31008f495a8e2fe2add\",\"name\":\"Redactie Deltavissers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\/\/www.deltavissers.nl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g\",\"caption\":\"Redactie Deltavissers\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Steiger Neeltje Jans weer even buiten dienst - Deltavissers Digitaal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/","og_locale":"nl_BE","og_type":"article","og_title":"Steiger Neeltje Jans weer even buiten dienst - Deltavissers Digitaal","og_description":"Steiger Neeltje Jans weer even buiten dienst Update planning en de uit te voeren werkzaamheden aan de steigers op Neeltje&#46;&#46;&#46;","og_url":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/","og_site_name":"Deltavissers Digitaal","article_publisher":"https:\/\/www.facebook.com\/Deltavissers-964812903597229\/","article_published_time":"2024-04-22T19:51:31+00:00","article_modified_time":"2024-04-22T19:51:32+00:00","og_image":[{"width":750,"height":370,"url":"http:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten.jpg","type":"image\/jpeg"}],"author":"Redactie Deltavissers","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Redactie Deltavissers","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#article","isPartOf":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/"},"author":{"name":"Redactie Deltavissers","@id":"https:\/\/www.deltavissers.nl\/#\/schema\/person\/0e0e972c446ec31008f495a8e2fe2add"},"headline":"Steiger Neeltje Jans weer even buiten dienst","datePublished":"2024-04-22T19:51:31+00:00","dateModified":"2024-04-22T19:51:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/"},"wordCount":120,"image":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg","keywords":["steiger Neeltje jans"],"articleSection":["Actueel"],"inLanguage":"nl-BE"},{"@type":"WebPage","@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/","url":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/","name":"Steiger Neeltje Jans weer even buiten dienst - Deltavissers Digitaal","isPartOf":{"@id":"https:\/\/www.deltavissers.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#primaryimage"},"image":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg","datePublished":"2024-04-22T19:51:31+00:00","dateModified":"2024-04-22T19:51:32+00:00","author":{"@id":"https:\/\/www.deltavissers.nl\/#\/schema\/person\/0e0e972c446ec31008f495a8e2fe2add"},"breadcrumb":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#primaryimage","url":"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg","contentUrl":"https:\/\/www.deltavissers.nl\/wp-content\/uploads\/2022\/11\/steiger-RWS-Neeltje-Jans-buiten_topic2.jpg","width":350,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/www.deltavissers.nl\/index.php\/2024\/04\/22\/steiger-neeltje-jans-weer-even-buiten-dienst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deltavissers.nl\/"},{"@type":"ListItem","position":2,"name":"Steiger Neeltje Jans weer even buiten dienst"}]},{"@type":"WebSite","@id":"https:\/\/www.deltavissers.nl\/#website","url":"https:\/\/www.deltavissers.nl\/","name":"Deltavissers Digitaal","description":"Webstek van Bootvisvereniging Zuid-West Nederland","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deltavissers.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Person","@id":"https:\/\/www.deltavissers.nl\/#\/schema\/person\/0e0e972c446ec31008f495a8e2fe2add","name":"Redactie Deltavissers","image":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/www.deltavissers.nl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57f75d85ae35472c7e3e4917c3345798b91667500277cf650c28cd5e3c0e48a2?s=96&d=mm&r=g","caption":"Redactie Deltavissers"}}]}},"_links":{"self":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/posts\/5435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/comments?post=5435"}],"version-history":[{"count":4,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/posts\/5435\/revisions"}],"predecessor-version":[{"id":5439,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/posts\/5435\/revisions\/5439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/media\/4428"}],"wp:attachment":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/media?parent=5435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/categories?post=5435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/tags?post=5435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}