{"id":222,"count":3,"description":"","link":"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/","name":"steiger Neeltje jans","slug":"steiger-neeltje-jans","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>steiger Neeltje jans Archives - Deltavissers Digitaal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"steiger Neeltje jans Archives - Deltavissers Digitaal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/\" \/>\n<meta property=\"og:site_name\" content=\"Deltavissers Digitaal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/\",\"url\":\"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/\",\"name\":\"steiger Neeltje jans Archives - Deltavissers Digitaal\",\"isPartOf\":{\"@id\":\"https:\/\/www.deltavissers.nl\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/#breadcrumb\"},\"inLanguage\":\"nl-BE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.deltavissers.nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"steiger Neeltje jans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.deltavissers.nl\/#website\",\"url\":\"https:\/\/www.deltavissers.nl\/\",\"name\":\"Deltavissers Digitaal\",\"description\":\"Webstek van Bootvisvereniging Zuid-West Nederland\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.deltavissers.nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"steiger Neeltje jans Archives - Deltavissers Digitaal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/","og_locale":"nl_BE","og_type":"article","og_title":"steiger Neeltje jans Archives - Deltavissers Digitaal","og_url":"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/","og_site_name":"Deltavissers Digitaal","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/","url":"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/","name":"steiger Neeltje jans Archives - Deltavissers Digitaal","isPartOf":{"@id":"https:\/\/www.deltavissers.nl\/#website"},"breadcrumb":{"@id":"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/#breadcrumb"},"inLanguage":"nl-BE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.deltavissers.nl\/index.php\/tag\/steiger-neeltje-jans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deltavissers.nl\/"},{"@type":"ListItem","position":2,"name":"steiger Neeltje jans"}]},{"@type":"WebSite","@id":"https:\/\/www.deltavissers.nl\/#website","url":"https:\/\/www.deltavissers.nl\/","name":"Deltavissers Digitaal","description":"Webstek van Bootvisvereniging Zuid-West Nederland","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deltavissers.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"}]}},"_links":{"self":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/tags\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.deltavissers.nl\/index.php\/wp-json\/wp\/v2\/posts?tags=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}